{"id":6,"count":1,"description":"","link":"https:\/\/unikondemo.wprealizer.com\/rtl\/category\/digital-marketing\/","name":"Digital Marketing","slug":"digital-marketing","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/unikondemo.wprealizer.com\/rtl\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unikondemo.wprealizer.com\/rtl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/unikondemo.wprealizer.com\/rtl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/unikondemo.wprealizer.com\/rtl\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}